{"id":138204,"date":"2024-07-04T09:48:00","date_gmt":"2024-07-04T07:48:00","guid":{"rendered":"https:\/\/poloniaoberoesterreich.com\/wp\/?p=138204"},"modified":"2025-03-24T11:07:16","modified_gmt":"2025-03-24T10:07:16","slug":"julian-gaborek-botschafter-polskosci-w-tvp-polonia-programm-kierunek-zachod","status":"publish","type":"post","link":"https:\/\/poloniaoberoesterreich.com\/de\/filmgalerie\/julian-gaborek-botschafter-polskosci-w-tvp-polonia-programm-kierunek-zachod\/","title":{"rendered":"Julian Gaborek - Botschafter des Polentums auf TVP Polonia in der Sendung \"Kierunek Zach\u00f3d\"."},"content":{"rendered":"<p><strong>JULIAN GABOREK - BOTSCHAFTER POLENS AUF TVP POLEN IN DER SENDUNG \"RICHTUNG WEST\"<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/kierunekzachod.tvp.pl\/79115332\/ambasador-polskosci-julian-gaborek\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/kierunekzachod.tvp.pl\/79115332\/ambasador-polskosci-julian-gaborek<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"864\" height=\"486\" src=\"https:\/\/poloniaoberoesterreich.com\/wp-content\/uploads\/2024\/09\/Julian-Gaborek-Ambasador-Polskosci-w-TVP-Polonia-w-programie-\u201eKierunek-Zachodni.jpeg\" alt=\"julian gaborek botschafter von polen auf tvp polonia in der sendung &quot;richtung west&quot;\" class=\"wp-image-138208\" srcset=\"\" sizes=\"(max-width: 864px) 100vw, 864px\" data-srcset=\"\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>JULIAN GABOREK - BOTSCHAFTER POLENS AUF TVP POLEN IN DER SENDUNG \"RICHTUNG WEST\"<\/p>","protected":false},"author":1,"featured_media":138208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[99,56],"tags":[],"class_list":{"0":"post-138204","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-2024-film-galeria","8":"category-film-galeria"},"_links":{"self":[{"href":"https:\/\/poloniaoberoesterreich.com\/de\/wp-json\/wp\/v2\/posts\/138204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poloniaoberoesterreich.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poloniaoberoesterreich.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poloniaoberoesterreich.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/poloniaoberoesterreich.com\/de\/wp-json\/wp\/v2\/comments?post=138204"}],"version-history":[{"count":0,"href":"https:\/\/poloniaoberoesterreich.com\/de\/wp-json\/wp\/v2\/posts\/138204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poloniaoberoesterreich.com\/de\/wp-json\/wp\/v2\/media\/138208"}],"wp:attachment":[{"href":"https:\/\/poloniaoberoesterreich.com\/de\/wp-json\/wp\/v2\/media?parent=138204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poloniaoberoesterreich.com\/de\/wp-json\/wp\/v2\/categories?post=138204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poloniaoberoesterreich.com\/de\/wp-json\/wp\/v2\/tags?post=138204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}